{"id":183,"date":"2020-08-17T01:54:33","date_gmt":"2020-08-17T01:54:33","guid":{"rendered":"https:\/\/mipejahotel.co.ke\/?page_id=183"},"modified":"2021-02-10T09:31:55","modified_gmt":"2021-02-10T09:31:55","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"183\" class=\"elementor elementor-183\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46e3e25d elementor-section-height-min-height elementor-section-items-top elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default\" data-id=\"46e3e25d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79857fde\" data-id=\"79857fde\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-facb775 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"facb775\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:reservations@mipejahotel.co.ke\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">reservations@mipejahotel.co.ke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+254746313233\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+254 746 313 233<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+254734313233\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+254 734 313 233<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34f611ed\" data-id=\"34f611ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8b4272 e-grid-align-right elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"f8b4272\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-0411e5e\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-674f0c0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-grow elementor-repeater-item-e094f70\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73d86e79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73d86e79\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7bd65526\" data-id=\"7bd65526\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3de546de elementor-widget elementor-widget-theme-site-logo\" data-id=\"3de546de\" data-element_type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1117d2d2 elementor-widget elementor-widget-nav-menu\" data-id=\"1117d2d2\" data-element_type=\"widget\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-73061697\" data-id=\"73061697\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cc1b9d animated-slow elementor-invisible elementor-widget elementor-widget-google_maps\" data-id=\"9cc1b9d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=0.454137%2C%2034.143128&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"0.454137, 34.143128\"\n\t\t\t\t\taria-label=\"0.454137, 34.143128\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8f060 elementor-widget elementor-widget-heading\" data-id=\"4b8f060\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contact Us<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-718b31f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"718b31f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a14f675\" data-id=\"a14f675\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa53a19 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"fa53a19\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Off Malaba-Busia Road, Busia County, Kenya<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+254746313233\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+254 746 313 233<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+254%20734%20313%20233\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+254 734 313 233<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">reservations@mipejahotel.co.ke<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d696af\" data-id=\"9d696af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-915d74f elementor-invisible elementor-widget elementor-widget-form\" data-id=\"915d74f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<footer class=\"elementor-section elementor-top-section elementor-element elementor-element-3062cf3f elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3062cf3f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51f8b5f5\" data-id=\"51f8b5f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5541b95e elementor-widget elementor-widget-heading\" data-id=\"5541b95e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00a9 2020 Mipeja Hotel. All Rights Reserved<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-692acd2a\" data-id=\"692acd2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78538ea0 elementor-widget elementor-widget-heading\" data-id=\"78538ea0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Designed by Koimink Solutions<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/footer>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>reservations@mipejahotel.co.ke +254 746 313 233 +254 734 313 233 Facebook Twitter Youtube Contact Us Off Malaba-Busia Road, Busia County, Kenya +254 746 313 233 +254 734 313 233 reservations@mipejahotel.co.ke \u00a9 2020 Mipeja Hotel. All Rights Reserved Designed by Koimink Solutions<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-183","page","type-page","status-publish","hentry","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact Us<\/title>\n<meta name=\"description\" content=\"Contact Us. Address: Busia - Malaba Road, Busia County, Kenya Phone: +254 746 313 233, +254 734 313 233\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us\" \/>\n<meta property=\"og:description\" content=\"Contact Us. Address: Busia - Malaba Road, Busia County, Kenya Phone: +254 746 313 233, +254 734 313 233\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Mipeja Hotel\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T09:31:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/\",\"url\":\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/\",\"name\":\"Contact Us\",\"isPartOf\":{\"@id\":\"https:\/\/mipejahotel.co.ke\/#website\"},\"datePublished\":\"2020-08-17T01:54:33+00:00\",\"dateModified\":\"2021-02-10T09:31:55+00:00\",\"description\":\"Contact Us. Address: Busia - Malaba Road, Busia County, Kenya Phone: +254 746 313 233, +254 734 313 233\",\"breadcrumb\":{\"@id\":\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mipejahotel.co.ke\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mipejahotel.co.ke\/#website\",\"url\":\"https:\/\/mipejahotel.co.ke\/\",\"name\":\"Mipeja Hotel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mipejahotel.co.ke\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mipejahotel.co.ke\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mipejahotel.co.ke\/#organization\",\"name\":\"Mipeja Hotel\",\"url\":\"https:\/\/mipejahotel.co.ke\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mipejahotel.co.ke\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mipejahotel.co.ke\/wp-content\/uploads\/2020\/08\/MIPEJA-HOTEL-OFFICIAL-LOGO-2.png\",\"contentUrl\":\"https:\/\/mipejahotel.co.ke\/wp-content\/uploads\/2020\/08\/MIPEJA-HOTEL-OFFICIAL-LOGO-2.png\",\"width\":779,\"height\":1008,\"caption\":\"Mipeja Hotel\"},\"image\":{\"@id\":\"https:\/\/mipejahotel.co.ke\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us","description":"Contact Us. Address: Busia - Malaba Road, Busia County, Kenya Phone: +254 746 313 233, +254 734 313 233","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/","og_locale":"en_US","og_type":"article","og_title":"Contact Us","og_description":"Contact Us. Address: Busia - Malaba Road, Busia County, Kenya Phone: +254 746 313 233, +254 734 313 233","og_url":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/","og_site_name":"Mipeja Hotel","article_modified_time":"2021-02-10T09:31:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/","url":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/","name":"Contact Us","isPartOf":{"@id":"https:\/\/mipejahotel.co.ke\/#website"},"datePublished":"2020-08-17T01:54:33+00:00","dateModified":"2021-02-10T09:31:55+00:00","description":"Contact Us. Address: Busia - Malaba Road, Busia County, Kenya Phone: +254 746 313 233, +254 734 313 233","breadcrumb":{"@id":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mipejahotel.co.ke\/index.php\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mipejahotel.co.ke\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/mipejahotel.co.ke\/#website","url":"https:\/\/mipejahotel.co.ke\/","name":"Mipeja Hotel","description":"","publisher":{"@id":"https:\/\/mipejahotel.co.ke\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mipejahotel.co.ke\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mipejahotel.co.ke\/#organization","name":"Mipeja Hotel","url":"https:\/\/mipejahotel.co.ke\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mipejahotel.co.ke\/#\/schema\/logo\/image\/","url":"https:\/\/mipejahotel.co.ke\/wp-content\/uploads\/2020\/08\/MIPEJA-HOTEL-OFFICIAL-LOGO-2.png","contentUrl":"https:\/\/mipejahotel.co.ke\/wp-content\/uploads\/2020\/08\/MIPEJA-HOTEL-OFFICIAL-LOGO-2.png","width":779,"height":1008,"caption":"Mipeja Hotel"},"image":{"@id":"https:\/\/mipejahotel.co.ke\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/pages\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":28,"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/pages\/183\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/pages\/183\/revisions\/542"}],"wp:attachment":[{"href":"https:\/\/mipejahotel.co.ke\/index.php\/wp-json\/wp\/v2\/media?parent=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}